
{"id":560253,"date":"2024-05-22T21:00:31","date_gmt":"2024-05-23T01:00:31","guid":{"rendered":"https:\/\/qanon-news.com\/?p=560253"},"modified":"2024-05-22T21:00:42","modified_gmt":"2024-05-23T01:00:42","slug":"footage-of-police-arresting-former-red-sox-pitcher-after-he-attempted-to-meet-an-underage-girl","status":"publish","type":"post","link":"https:\/\/qanon-news.com\/en\/footage-of-police-arresting-former-red-sox-pitcher-after-he-attempted-to-meet-an-underage-girl\/","title":{"rendered":"Footage of police arresting former Red Sox pitcher after he attempted to meet an underage girl"},"content":{"rendered":"<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Footage of police arresting former Red Sox pitcher after he attempted to meet an underage girl\" src=\"https:\/\/rumble.com\/embed\/v4u45lu\/#?secret=HgaQ85pD8Y\" data-secret=\"HgaQ85pD8Y\" width=\"1280\" height=\"720\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":560254,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,32,188],"tags":[],"class_list":["post-560253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arrested","category-pedophile","category-sports"],"_links":{"self":[{"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/posts\/560253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/comments?post=560253"}],"version-history":[{"count":0,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/posts\/560253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/media\/560254"}],"wp:attachment":[{"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/media?parent=560253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/categories?post=560253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/tags?post=560253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}