
{"id":699785,"date":"2025-09-02T23:57:00","date_gmt":"2025-09-03T03:57:00","guid":{"rendered":"https:\/\/qanon-news.com\/?p=699785"},"modified":"2025-09-02T23:57:00","modified_gmt":"2025-09-03T03:57:00","slug":"the-creepiest-ted-talk-ever","status":"publish","type":"post","link":"https:\/\/qanon-news.com\/en\/the-creepiest-ted-talk-ever\/","title":{"rendered":"The Creepiest TED Talk Ever?"},"content":{"rendered":"<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"The Creepiest TED Talk Ever?\" src=\"https:\/\/rumble.com\/embed\/v6w7xq4\/#?secret=JyNgDz7gSG\" data-secret=\"JyNgDz7gSG\" width=\"960\" height=\"540\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":699786,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1076,321,34],"tags":[],"class_list":["post-699785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-awakening-with-jp","category-lgbt","category-transgender"],"_links":{"self":[{"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/posts\/699785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/comments?post=699785"}],"version-history":[{"count":0,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/posts\/699785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/media\/699786"}],"wp:attachment":[{"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/media?parent=699785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/categories?post=699785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qanon-news.com\/en\/wp-json\/wp\/v2\/tags?post=699785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}